{"id":184,"date":"2012-07-27T06:46:21","date_gmt":"2012-07-27T06:46:21","guid":{"rendered":"http:\/\/www.topfruits.de\/aktuell2\/2012\/07\/27\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\/"},"modified":"2025-12-02T15:37:09","modified_gmt":"2025-12-02T14:37:09","slug":"das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl","status":"publish","type":"post","link":"https:\/\/www.topfruits.de\/aktuell\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\/","title":{"rendered":"Das milchsaure Getreideschrot-M\u00fcsli nach Dr. Johannes Kuhl"},"content":{"rendered":"<p>Leider ist das B\u00fcchlein von Dr. Johannes Kuhl &#8222;Das milchsaure Getreideschrot-M\u00fcsli, Komplexer milchsaurer Getreideschimmel &#8211; ein Strahlenschutz und Zellregenerationsmittel&#8220; nicht mehr im Handel erh\u00e4ltlich. Auch antiquarisch kaum noch zu finden. Aus diesem Grund und weil wir immer wieder von Kunden gefragt werden, ob wir Informationen dazu haben wie man den milchsauren Getreideschimmel bzw. dieses M\u00fcsli herstellt, m\u00f6chte ich hier ein paar Informationen aus besagtem B\u00fcchlein weiter geben.<\/p>\n<p><strong>Nach Kuhl\u00b4s Erfahrungen stellt der Brot- und Getreideschimmel das gr\u00f6sste zellatmungssch\u00fctzende und zellamtmungsregenerierende Mittel dar, welches uns die Natur schenkt.<\/strong><\/p>\n<p>Bereits die alten \u00c4gypter heilten vor 5000 Jahren viele Krankheiten damit. Zur Information, Dr. med. Johannnes Kuhl war in den 1950er und 1960er Jahren ein bekannter Krebsarzt, der mit seiner Kostform basierend auf gesunder Vollwertkost und einem hohen Anteil milchsauer fermentierter Lebensmittel, erstaunliche und nicht f\u00fcr m\u00f6glich gehaltene Heilungserfolge erzielte. Er hat sich zeitlebens der Beobachtung und Beweisf\u00fchrung gewidmet die zu diesen Erfolgen gef\u00fchrt haben. Laut Kuhl und auch anderer ganzheitlicher Krebsmediziner, ist Krebs eine Zellatmungsst\u00f6rung, welche zur grenzenlosen Wucherung von Krebszellen f\u00fchrt. Als Basistherapie muss deshalb mit allen Mitteln die Zellatmung im Organismus verbessert werden. Alle Massnahmen welche dazu in der Lage sind haben bei Krebs eine hilfreiche und heilende Wirkung und sind \u00fcberdies in der Pr\u00e4vention von Krebserkrankungen von unsch\u00e4tzbarem Wert.<\/p>\n<p><strong>Die Herstellung des milchsauren Schimmelschrot-M\u00fcslis (Das milchsaure Getreideschrot-M\u00fcsli S.29)<\/strong> <br \/>\nM\u00f6glichst gesund gewachsenes, vollwertiges Getreide aus biologischem Anbau, wird in einer Getreidem\u00fchle <strong>grob geschrotet<\/strong> und dann mit 30% ungekochtem handwarmen Trinkwasser (zB 100g Schrot + 30ccm Wasser) \u00fcbersch\u00fcttet und gr\u00fcndlich mit einer Gabel durchmischt. Die zu verwendende Menge Getreideschrot richtet sich nach dem Appetit des Einzelnen, ich empfehle im Allgemeinen 60g t\u00e4glich pro Person. Dieser Schrotbrei wird in einer Glasschale angesetzt und diese unbedeckt an einem warmen (20-25Grad), m\u00f6glichst staubfreien Ort gestellt. Anmerk MM: Ich w\u00fcrde zum Schutz vor Fliegen udgl die Schale mit einem d\u00fcnnen K\u00fcchenhandtuch oder einem St\u00fcck Gaze abdecken.<\/p>\n<p>Der Schrot bleibt je nach Temp. so f\u00fcr 5 Tage stehen. Nach dieser Zeit der G\u00e4rungs- und Verpilzungsvorg\u00e4nge wird der Schrot, der wieder trocken geworden und leicht zusammen gebacken ist, mit einer Gabel zerdr\u00fcckt. Nun beginnt man mit der Zubereitung des vergorenen (Anmerk. MM fermentierten) und verpilzten Schrotes zu einem appetitlichen, tafelfertigen M\u00fcsli. Dem Geschmack und der Zubereitungsart wird dabei breiter Spielraum gelassen.<\/p>\n<p>Allgemein ist ein Anrichten mit Wasser oder Buttermilch erw\u00fcnscht. Auch naturreine ungezuckerte Frucht- oder Gem\u00fcses\u00e4fte k\u00f6nnen als Fl\u00fcssigkeit verwendet werden. Geschmackliche Variationen erreicht man mit Zus\u00e4tzen von N\u00fcssen, geriebenen \u00c4pfeln oder anderem zerkleinertem Obst. Beim Anrichten mit Obsts\u00e4ften, oder geriebenem Apfel ist zu beachten dass der Genuss sofort nach dem Anrichten erfolgen soll, um das Entstehen unerw\u00fcnschter Verbindungen zu vermeiden, welche Geschmack und Bek\u00f6mmlichkeit beeintr\u00e4chtigen. Zum S\u00fcssen ist R\u00fcbensyrup oder Bienenhonig empfehlenswert (Anm. MM: Agaven- oder Apfeldicksaft gilt auch \ud83d\ude09<\/p>\n<p>Dieses M\u00fcsli wind in bezug auf seinen universellen Wirkstoff- und Vitalstoffreichtum von keinem pharmazeutischen oder biologischen N\u00e4hrpr\u00e4parat oder irgendeiner Speise \u00fcbertroffen. Als vollwertige und qualit\u00e4tserh\u00f6hte, alle N\u00e4hr- und Vitalstoffe enthaltende Gesundheits- und Krankenkost, kann sein t\u00e4glicher Genuss nicht dringend genug empfohlen werden. Das Kuhl M\u00fcsli kann als Fr\u00fchst\u00fcck oder Abendmahlzeit genossen werden, oder als Vorspeise vor dem Mittag- oder Abendessen.<\/p>\n<p>Kuhl schreibt: Man erschrecke nicht, wenn man auf, oder in dem 5 Tage alten angesetzten Getreideschrot einen massiven, buntfarbigen Schimmel vorfindet. Diese Schimmelbildung ist erstrebt und somit erw\u00fcnscht und das Produkt genie\u00dfbar, wenn kein fauliger Geruch vorhanden ist. Ein fauliger Geruch beruht immer auf einer bakteriellen Zersetzung. Schimmelpilze sind nie F\u00e4ulniserreger. Das fertige Ergebnis muss vielmehr einen mosig-pilzigen Waldboden Geruch haben.<\/p>\n<p>Um t\u00e4glich einen genussfertigen Brei herstellen zu k\u00f6nnen, muss man t\u00e4glich, m\u00f6glichst zur selben Zeit frisches Schrot ansetzen, damit man immer 6 Tage alten, fertig fermentierten Schrot hat.<\/p>\n<p>Auch ist es m\u00f6glich, eine gr\u00f6ssere Menge milchsauren Getreideschimmelschrot herzustellen und diesen nach Fertigstellung vollst\u00e4ndig zu trocknen. Dies geschieht indem man den unten noch feuchten Schimmelkuchen wendet, und so von beiden Seiten an einem trockenen und luftigen Platz gut durchtrocknen l\u00e4sst, ggf. auf einem Kuchendraht. Zerbrochen und in dicht schliessenden Beh\u00e4ltern, k\u00fchl und dunkel kann dieser dann monatelang aufbewahrt und verwendet werden, ohne dass seine Wirkung geschm\u00e4lert wird.<\/p>\n<p>Zur Herstellung des milchsauren M\u00fcslis kann jeder frisch gemahlene Getreideschrot aus ganzen keimf\u00e4higen K\u00f6rnern verwendet werden. Nicht geeignet sind industriell vorgefertigte Flocken, da sich auf dieser Basis keine einwandfreie Fermentierung und Schimmelbildung vollzieht.<\/p>\n<p><strong>Die drei h\u00e4ufigsten Fehler, welche die Schimmelbildung beeintr\u00e4chtigen:<\/strong> <br \/>\n<strong>1.<\/strong> Anstatt grob geschrotetes Korn wird zu fein gemahlenes Material verwendet. Unter diesen Umst\u00e4nden bildet sich beim Zusetzen des Wasser ein &#8222;Mehlpapp&#8220; welcher die falsche Ausgangsbasis f\u00fcr den milchsauren Getreideschimmel ist. Ein einwandfreies Ergebnis ist nur zu erwarten, wenn der Schrot so grob ist dass Durch und Durch ausreichend Luft und Sauerstoff auf die Masse einwirken kann.<\/p>\n<p><strong>2.<\/strong> Die Schimmelbildung wird durch Zufuhr von frischer Luft gef\u00f6rdert aber durch Zugluft gehemmt oder unterbunden.Die Schrotschalen sind also am Ort der Aufstellung vor Zugluft zu sch\u00fctzen.<\/p>\n<p><strong>3.<\/strong> Die vorgeschriebene Fl\u00fcssigkeitsmenge ist genau einzuhalten. Es darf nicht eine beliebige, nach Gutd\u00fcnken gew\u00e4hlte Wassermenge hinzugegeben werden. Die Schimmelbildung geht sonst, insbesondere bei zuviel Wasser, in F\u00e4ulnis und Zersetzung \u00fcber und der Ansatz ist dann verdorben.<\/p>\n<p><strong>Ist Schimmel giftig? &#8211; eine Stellungnahme:<\/strong> <br \/>\nDer dauerhafte Genuss von verschimmelten H\u00fclsenfr\u00fcchten (Erdn\u00fcsse, Soja) und N\u00fcssen ist in vielen Entwicklungsl\u00e4ndern die Ursache f\u00fcr das geh\u00e4ufte Auftreten von Leberkrebs bei Tieren und Menschen. Der dort entstehende Schimmelpilz Aspergillus flavus erzeugt Aflatoxine, welche krebserregend sind (zumindest wenn der Verzehr mit einem dauerhaft hohen Konsum an vornehmlich tierischen Einweis einhergeht (Quelle: Die China Study).<\/p>\n<p>Entscheidend f\u00fcr die Wirkung des Schimmels bzw. der eventuell vorkommenden &#8222;Aflatoxine&#8220; ist jedoch das Milieu. <strong>In einem milchsauren Milieu, wie es bei der Erzeugung, des nach Anweisung hergestellten Getreideschimmels entsteht, ist Aflatoxin nie giftig. <\/strong>Ebenso wenig wie bei den in oder auf milchsaurem Milieu wachsenden Edelschimmeln von Schimmelk\u00e4sesorten wie Camembert, Roquefort oder Gorgonzola.<\/p>\n<p><strong>Kuhl schreibt weiter:<\/strong> <br \/>\nIn der 10j\u00e4hrigen Praxiserfahrung an tausenden von Patienten und Hilfesuchenden haben wir mit der komplexen Getreideschimmel-Therapie selbst bei krebskranken grosse Heilerfolge, aber niemals Gesundheitssch\u00e4digungen gesehen.<\/p>\n<p>Der milchsaure, bunte Schimmel, der bis heute in der Ern\u00e4hrungswissenschaft und der Medizin in seiner \u00fcberragenden, krankheitsvorbeugenden und heilenden , zellatmung sch\u00fctzenden und regenerierenden Wirkung noch nicht erkannt, ja allgemein sogar als gef\u00e4hrlich und giftig angesehen wurde, wird in der Zukunft seinen Siegeszug &#8230; antreten. Was ich bis jetzt bei seiner t\u00e4glichen Anwendung erlebe, habe ich bei seiner Einf\u00fchrung in der Humanmedizin weder zu erhoffen gewagt, noch f\u00fcr m\u00f6glich gehalten.<\/p>\n<p>Jeder trockene (nicht der nasse faulig riechende, bakteriell zersetzte) Schimmel, gleich welcher Farbe, ist stets heilkr\u00e4ftig und nie gesundheitssch\u00e4dlich, noch giftig.<\/p>\n<p>Wer mehr lesen will zu den Erfahrungen und Therapievorschl\u00e4gen von Dr. Johannes Kuhl, liest am Besten sein Hauptwerk <a title=\"Eine erfolgreiche Arznei - und Ern\u00e4hrungsbehandlung gut- und b\u00f6sartiger Geschw\u00fclste - Dr. Johannes Kuhl\" href=\"\/produkt\/eine-erfolgreiche-arznei-und-ernaehrungsbehandlung-gut-und-boesartiger-geschwuelste-dr-johannes-kuhl-nachdruck\/\">&#8222;Eine erfolgreiche Arznei &#8211; und Ern\u00e4hrungsbehandlung gut- und b\u00f6sartiger Geschw\u00fclste&#8220;<\/a> Obwohl im Stil der 1960er Jahre geschrieben, enth\u00e4lt das Buch eine F\u00fclle hilfreicher Informationen an denen sich der Krebskranke, oder um Pr\u00e4vention bem\u00fchte orientieren kann. Ausserdem m\u00f6chte ich auf den Buchauszug <a title=\"Kuhl milchsaure Kostform bei Krebs\" href=\"http:\/\/www.aprikosen.info\/Kuhl_ernaehrung.htm\">&#8222;Gibt es eine Krebsdi\u00e4t&#8220; aus dem Titel &#8222;Dichtung und Wahrheit in der Krebsfrage&#8220;<\/a> hinweisen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leider ist das B\u00fcchlein von Dr. Johannes Kuhl &#8222;Das milchsaure Getreideschrot-M\u00fcsli, Komplexer milchsaurer Getreideschimmel &#8211; ein Strahlenschutz und Zellregenerationsmittel&#8220; nicht mehr im Handel erh\u00e4ltlich. Auch antiquarisch kaum noch zu finden. Aus diesem Grund und weil wir immer wieder von Kunden gefragt werden, ob wir Informationen dazu haben wie man den milchsauren Getreideschimmel bzw. dieses M\u00fcsli herstellt, m\u00f6chte ich hier ein paar Informationen aus besagtem B\u00fcchlein weiter geben. Nach Kuhl\u00b4s Erfahrungen stellt der Brot- und Getreideschimmel&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[6,4],"tags":[59,603,604,602,386,49,224,600,197,205,334,601],"class_list":["post-184","post","type-post","status-publish","format-standard","hentry","category-allgemeines","category-vitalstoffkueche","tag-aflatoxine","tag-apfeldicksaft","tag-einweis","tag-getreideschrot","tag-huelsenfruechte","tag-nuesse","tag-obst","tag-schimmelschrot-muesli","tag-vitalstoffreich","tag-vitamine","tag-vollkornprodukte","tag-vollwertig"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Das milchsaure Getreideschrot-M\u00fcsli nach Dr. Johannes Kuhl - Topfruits Infothek<\/title>\n<meta name=\"description\" content=\"Milchsaure Getreideschrot-M\u00fcsli nach Dr. Johannes Kuhl - erfahren Sie hier mehr zum besonderen M\u00fcsli.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.topfruits.de\/aktuell\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Das milchsaure Getreideschrot-M\u00fcsli nach Dr. Johannes Kuhl - Topfruits Infothek\" \/>\n<meta property=\"og:description\" content=\"Milchsaure Getreideschrot-M\u00fcsli nach Dr. Johannes Kuhl - erfahren Sie hier mehr zum besonderen M\u00fcsli.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.topfruits.de\/aktuell\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\/\" \/>\n<meta property=\"og:site_name\" content=\"Topfruits Infothek\" \/>\n<meta property=\"article:published_time\" content=\"2012-07-27T06:46:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-02T14:37:09+00:00\" \/>\n<meta name=\"author\" content=\"topfruits\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\\\/\"},\"author\":{\"name\":\"topfruits\",\"@id\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/#\\\/schema\\\/person\\\/53eefe715df576f52e381f2c48d2bcd5\"},\"headline\":\"Das milchsaure Getreideschrot-M\u00fcsli nach Dr. Johannes Kuhl\",\"datePublished\":\"2012-07-27T06:46:21+00:00\",\"dateModified\":\"2025-12-02T14:37:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\\\/\"},\"wordCount\":1252,\"publisher\":{\"@id\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/#organization\"},\"keywords\":[\"Aflatoxine\",\"Apfeldicksaft\",\"Einweis\",\"Getreideschrot\",\"H\u00fclsenfr\u00fcchte\",\"N\u00fcsse\",\"Obst\",\"Schimmelschrot-M\u00fcsli\",\"vitalstoffreich\",\"Vitamine\",\"Vollkornprodukte\",\"vollwertig\"],\"articleSection\":[\"Allgemeines\",\"Vitalstoffk\u00fcche\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\\\/\",\"url\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\\\/\",\"name\":\"Das milchsaure Getreideschrot-M\u00fcsli nach Dr. Johannes Kuhl - Topfruits Infothek\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/#website\"},\"datePublished\":\"2012-07-27T06:46:21+00:00\",\"dateModified\":\"2025-12-02T14:37:09+00:00\",\"description\":\"Milchsaure Getreideschrot-M\u00fcsli nach Dr. Johannes Kuhl - erfahren Sie hier mehr zum besonderen M\u00fcsli.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Das milchsaure Getreideschrot-M\u00fcsli nach Dr. Johannes Kuhl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/#website\",\"url\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/\",\"name\":\"Topfruits Infothek\",\"description\":\"Topfruits informiert, Kunden und Ern\u00e4hrungsexperten berichten.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/#organization\",\"name\":\"Topfruits Infothek\",\"url\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Topfruits Infothek\"},\"image\":{\"@id\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/#\\\/schema\\\/person\\\/53eefe715df576f52e381f2c48d2bcd5\",\"name\":\"topfruits\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c8d61b34af338a3c16c0a2c56613a7eb821d48228926f6df511945c9bd995439?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c8d61b34af338a3c16c0a2c56613a7eb821d48228926f6df511945c9bd995439?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c8d61b34af338a3c16c0a2c56613a7eb821d48228926f6df511945c9bd995439?s=96&d=mm&r=g\",\"caption\":\"topfruits\"},\"url\":\"https:\\\/\\\/www.topfruits.de\\\/aktuell\\\/author\\\/topfruits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Das milchsaure Getreideschrot-M\u00fcsli nach Dr. Johannes Kuhl - Topfruits Infothek","description":"Milchsaure Getreideschrot-M\u00fcsli nach Dr. Johannes Kuhl - erfahren Sie hier mehr zum besonderen M\u00fcsli.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.topfruits.de\/aktuell\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\/","og_locale":"de_DE","og_type":"article","og_title":"Das milchsaure Getreideschrot-M\u00fcsli nach Dr. Johannes Kuhl - Topfruits Infothek","og_description":"Milchsaure Getreideschrot-M\u00fcsli nach Dr. Johannes Kuhl - erfahren Sie hier mehr zum besonderen M\u00fcsli.","og_url":"https:\/\/www.topfruits.de\/aktuell\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\/","og_site_name":"Topfruits Infothek","article_published_time":"2012-07-27T06:46:21+00:00","article_modified_time":"2025-12-02T14:37:09+00:00","author":"topfruits","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.topfruits.de\/aktuell\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\/#article","isPartOf":{"@id":"https:\/\/www.topfruits.de\/aktuell\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\/"},"author":{"name":"topfruits","@id":"https:\/\/www.topfruits.de\/aktuell\/#\/schema\/person\/53eefe715df576f52e381f2c48d2bcd5"},"headline":"Das milchsaure Getreideschrot-M\u00fcsli nach Dr. Johannes Kuhl","datePublished":"2012-07-27T06:46:21+00:00","dateModified":"2025-12-02T14:37:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.topfruits.de\/aktuell\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\/"},"wordCount":1252,"publisher":{"@id":"https:\/\/www.topfruits.de\/aktuell\/#organization"},"keywords":["Aflatoxine","Apfeldicksaft","Einweis","Getreideschrot","H\u00fclsenfr\u00fcchte","N\u00fcsse","Obst","Schimmelschrot-M\u00fcsli","vitalstoffreich","Vitamine","Vollkornprodukte","vollwertig"],"articleSection":["Allgemeines","Vitalstoffk\u00fcche"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.topfruits.de\/aktuell\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\/","url":"https:\/\/www.topfruits.de\/aktuell\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\/","name":"Das milchsaure Getreideschrot-M\u00fcsli nach Dr. Johannes Kuhl - Topfruits Infothek","isPartOf":{"@id":"https:\/\/www.topfruits.de\/aktuell\/#website"},"datePublished":"2012-07-27T06:46:21+00:00","dateModified":"2025-12-02T14:37:09+00:00","description":"Milchsaure Getreideschrot-M\u00fcsli nach Dr. Johannes Kuhl - erfahren Sie hier mehr zum besonderen M\u00fcsli.","breadcrumb":{"@id":"https:\/\/www.topfruits.de\/aktuell\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.topfruits.de\/aktuell\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.topfruits.de\/aktuell\/das-milchsaure-getreideschrot-muesli-nach-dr-johannes-kuhl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.topfruits.de\/aktuell\/"},{"@type":"ListItem","position":2,"name":"Das milchsaure Getreideschrot-M\u00fcsli nach Dr. Johannes Kuhl"}]},{"@type":"WebSite","@id":"https:\/\/www.topfruits.de\/aktuell\/#website","url":"https:\/\/www.topfruits.de\/aktuell\/","name":"Topfruits Infothek","description":"Topfruits informiert, Kunden und Ern\u00e4hrungsexperten berichten.","publisher":{"@id":"https:\/\/www.topfruits.de\/aktuell\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.topfruits.de\/aktuell\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.topfruits.de\/aktuell\/#organization","name":"Topfruits Infothek","url":"https:\/\/www.topfruits.de\/aktuell\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.topfruits.de\/aktuell\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Topfruits Infothek"},"image":{"@id":"https:\/\/www.topfruits.de\/aktuell\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.topfruits.de\/aktuell\/#\/schema\/person\/53eefe715df576f52e381f2c48d2bcd5","name":"topfruits","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c8d61b34af338a3c16c0a2c56613a7eb821d48228926f6df511945c9bd995439?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c8d61b34af338a3c16c0a2c56613a7eb821d48228926f6df511945c9bd995439?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c8d61b34af338a3c16c0a2c56613a7eb821d48228926f6df511945c9bd995439?s=96&d=mm&r=g","caption":"topfruits"},"url":"https:\/\/www.topfruits.de\/aktuell\/author\/topfruits\/"}]}},"_links":{"self":[{"href":"https:\/\/www.topfruits.de\/aktuell\/wp-json\/wp\/v2\/posts\/184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.topfruits.de\/aktuell\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.topfruits.de\/aktuell\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.topfruits.de\/aktuell\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.topfruits.de\/aktuell\/wp-json\/wp\/v2\/comments?post=184"}],"version-history":[{"count":1,"href":"https:\/\/www.topfruits.de\/aktuell\/wp-json\/wp\/v2\/posts\/184\/revisions"}],"predecessor-version":[{"id":8226,"href":"https:\/\/www.topfruits.de\/aktuell\/wp-json\/wp\/v2\/posts\/184\/revisions\/8226"}],"wp:attachment":[{"href":"https:\/\/www.topfruits.de\/aktuell\/wp-json\/wp\/v2\/media?parent=184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.topfruits.de\/aktuell\/wp-json\/wp\/v2\/categories?post=184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.topfruits.de\/aktuell\/wp-json\/wp\/v2\/tags?post=184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}